{"id":60553,"date":"2021-02-26T10:36:46","date_gmt":"2021-02-26T17:36:46","guid":{"rendered":"http:\/\/saitjournalism.ca\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004.jpg"},"modified":"2021-02-26T10:36:46","modified_gmt":"2021-02-26T17:36:46","slug":"20210222-s2-alliance-of-kitchen-mc-0004","status":"inherit","type":"attachment","link":"https:\/\/saitjournalism.ca\/thepress\/20210222-s2-alliance-of-kitchen-mc-0004\/","title":{"rendered":"20210222 S2 Alliance of Kitchen MC 0004"},"author":663,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-60553","attachment","type-attachment","status-inherit"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-300x200.jpg 300w, https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-1024x683.jpg 1024w, https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-768x512.jpg 768w, https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-1536x1024.jpg 1536w, https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<div class=\"mh-excerpt\"><p>Aman Singh Waraich in Lovely sweets at Saddleridge, Calgary, Alberta poses for an environmental portrait on February 22,2021 (Photo by Manpreet S. Chhabra\/The Press) <a class=\"mh-excerpt-more\" href=\"https:\/\/saitjournalism.ca\/thepress\/20210222-s2-alliance-of-kitchen-mc-0004\/\" title=\"20210222 S2 Alliance of Kitchen MC 0004\">[ READ MORE ]<\/a><\/p>\n<\/div>"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1707,"file":"2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-scaled.jpg","sizes":{"medium":{"file":"20210222-S2-Alliance-of-Kitchen-MC-0004-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-300x200.jpg"},"large":{"file":"20210222-S2-Alliance-of-Kitchen-MC-0004-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-1024x683.jpg"},"thumbnail":{"file":"20210222-S2-Alliance-of-Kitchen-MC-0004-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-150x150.jpg"},"medium_large":{"file":"20210222-S2-Alliance-of-Kitchen-MC-0004-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-768x512.jpg"},"1536x1536":{"file":"20210222-S2-Alliance-of-Kitchen-MC-0004-1536x1024.jpg","width":1536,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-1536x1024.jpg"},"2048x2048":{"file":"20210222-S2-Alliance-of-Kitchen-MC-0004-2048x1365.jpg","width":2048,"height":1365,"mime_type":"image\/jpeg","source_url":"https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-2048x1365.jpg"},"mh-magazine-slider":{"file":"20210222-S2-Alliance-of-Kitchen-MC-0004-1030x438.jpg","width":1030,"height":438,"mime_type":"image\/jpeg","source_url":"https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-1030x438.jpg"},"mh-magazine-content":{"file":"20210222-S2-Alliance-of-Kitchen-MC-0004-678x381.jpg","width":678,"height":381,"mime_type":"image\/jpeg","source_url":"https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-678x381.jpg"},"mh-magazine-large":{"file":"20210222-S2-Alliance-of-Kitchen-MC-0004-678x509.jpg","width":678,"height":509,"mime_type":"image\/jpeg","source_url":"https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-678x509.jpg"},"mh-magazine-medium":{"file":"20210222-S2-Alliance-of-Kitchen-MC-0004-326x245.jpg","width":326,"height":245,"mime_type":"image\/jpeg","source_url":"https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-326x245.jpg"},"mh-magazine-small":{"file":"20210222-S2-Alliance-of-Kitchen-MC-0004-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-80x60.jpg"},"full":{"file":"20210222-S2-Alliance-of-Kitchen-MC-0004-scaled.jpg","width":2560,"height":1707,"mime_type":"image\/jpeg","source_url":"https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-scaled.jpg"}},"image_meta":{"aperture":"5","credit":"Manpreet S. Chhabra","camera":"Canon EOS REBEL T3i","caption":"Aman Singh Waraich in Lovely sweets at Saddleridge, Calgary, Alberta poses for an environmental portrait on February 22,2021 (Photo by Manpreet S. Chhabra\/The Press)","created_timestamp":"1583379757","copyright":"\u00a92021 Manpreet S. Chhabra\/SAIT","focal_length":"18","iso":"400","shutter_speed":"0.033333333333333","title":"","orientation":"1","keywords":[]},"original_image":"20210222-S2-Alliance-of-Kitchen-MC-0004.jpg"},"post":null,"source_url":"https:\/\/saitjournalism.ca\/thepress\/wp-content\/uploads\/2021\/02\/20210222-S2-Alliance-of-Kitchen-MC-0004-scaled.jpg","_links":{"self":[{"href":"https:\/\/saitjournalism.ca\/thepress\/wp-json\/wp\/v2\/media\/60553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saitjournalism.ca\/thepress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/saitjournalism.ca\/thepress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/saitjournalism.ca\/thepress\/wp-json\/wp\/v2\/users\/663"}],"replies":[{"embeddable":true,"href":"https:\/\/saitjournalism.ca\/thepress\/wp-json\/wp\/v2\/comments?post=60553"}]}}